{"id":20273,"date":"2026-05-12T13:15:57","date_gmt":"2026-05-12T13:15:57","guid":{"rendered":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/?p=20273"},"modified":"2026-05-12T13:17:42","modified_gmt":"2026-05-12T13:17:42","slug":"goldfische-2","status":"publish","type":"post","link":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/goldfische-2\/","title":{"rendered":"Wie man uns unterst\u00fctzen kann .."},"content":{"rendered":"\n<p>Oft werden wir gefragt, wie man uns unterst\u00fctzen kann. Hier gibt es unterschiedliche M\u00f6glichkeiten, die wir Euch gerne kurz vorstellen.<\/p>\n\n\n\n<p>Eine Option dabei ist das <strong>Teaming<\/strong>. <\/p>\n\n\n\n<p><em>Mit 1 Euro monatlich k\u00f6nnt ihr unseren kleinen Tierschutzhof prima unterst\u00fctzen.<\/em><\/p>\n\n\n\n<p>Je mehr liebe Menschen mitmachen, je gr\u00f6\u00dfer die Unterst\u00fctzung. Aktuell haben wir 732 Teamer bei 14570 Followern. Vielleicht auch, weil diese Variante noch nicht so viele von Euch kennen?<\/p>\n\n\n\n<p>Bestimmt sind von unseren zahlreichen Followern noch einige bereit, uns mit 1 Euro monatlich zu unterst\u00fctzen oder? <\/p>\n\n\n\n<p>Hier geht es zur Anmeldung: <a rel=\"noreferrer noopener\" href=\"https:\/\/www.teaming.net\/tierschutzhof-karlsruhe?fbclid=IwZXh0bgNhZW0CMTAAYnJpZBEwbGE1Nm9sRXhSYUhWTGl2VHNydGMGYXBwX2lkEDIyMjAzOTE3ODgyMDA4OTIAAR42cmPsrj1lZBL8NAMKEwcOlAk91JjP2ZBtcYVVVgHURv6IxaFpYcHiyRVRwg_aem_65UaU2KWDXbq-mkmJUEn3g\" target=\"_blank\">https:\/\/www.teaming.net\/tierschutzhof-karlsruhe<\/a> <\/p>\n\n\n\n<p>Alternativ k\u00f6nnt ihr nat\u00fcrlich auch ganz klassich einen kleinen Dauerauftrag auf unser bekanntes Konto einrichten!<\/p>\n\n\n\n<p>Wir freuen uns \u00fcber Eure Unterst\u00fctzung.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oft werden wir gefragt, wie man uns unterst\u00fctzen kann. Hier gibt es unterschiedliche M\u00f6glichkeiten, die wir Euch gerne kurz vorstellen. Eine Option dabei ist das Teaming. Mit 1 Euro monatlich k\u00f6nnt ihr unseren kleinen Tierschutzhof prima unterst\u00fctzen. Je mehr liebe Menschen mitmachen, je gr\u00f6\u00dfer die Unterst\u00fctzung. Aktuell haben wir 732 Teamer bei 14570 Followern. Vielleicht&#8230;<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":[],"categories":[4],"tags":[125,138,139],"_links":{"self":[{"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/posts\/20273"}],"collection":[{"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/comments?post=20273"}],"version-history":[{"count":2,"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/posts\/20273\/revisions"}],"predecessor-version":[{"id":20275,"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/posts\/20273\/revisions\/20275"}],"wp:attachment":[{"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/media?parent=20273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/categories?post=20273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/tags?post=20273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}