{"id":20285,"date":"2026-05-13T12:53:19","date_gmt":"2026-05-13T12:53:19","guid":{"rendered":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/?p=20285"},"modified":"2026-05-13T12:53:20","modified_gmt":"2026-05-13T12:53:20","slug":"fundhund","status":"publish","type":"post","link":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/fundhund\/","title":{"rendered":"Neuzugang &#8211; Aufregung heute Morgen auf dem Tierschutzhof Karlsruhe"},"content":{"rendered":"\n<p>Am fr\u00fchen Morgen des 11. Mai wurde bei uns am Tor ein Hund angebunden!<\/p>\n\n\n\n<p>Sicherlich ist dies eine unsch\u00f6ne Situation: der Hund verliert seinen Bezugsmenschen, seinen Halt!<\/p>\n\n\n\n<p>F\u00fcr uns bedeutet dies Unsicherheit betreffend das Tier, seinen Gesundheitszustand. \u00dcber die steigenden Kosten f\u00fcr uns und die Verantwortung f\u00fcr ein noch unbekannte Tier \u2013 dar\u00fcber brauchen wir nicht sprechen.<\/p>\n\n\n\n<p>In vielen Kommentaren wird nun teils sehr \u00fcbel \u00fcber diesen Menschen geredet, ohne zu wissen, was diesen dazu bewogen hat, den Hund bei uns anzubinden.<\/p>\n\n\n\n<p>Immerhin hatte diese Person so viel R\u00fcckgrat, den Hund nicht einfach irgendwo anzubinden oder laufen zu lassen. Diese Person hat den Hund unmittelbar im Eingangsbereich zu unserem Hof angebunden. Bereits vier Minuten sp\u00e4ter konnten wir diesen dann sichern und in einem unserer Gehege unterbringen.<\/p>\n\n\n\n<p>Fakt: Es ist heute fast unm\u00f6glich, sein Haustier in einem Tierheim abzugeben, um den offiziellen Weg zu gehen. 90 % der Tierheime bei uns in der Umgebung sind voll.<\/p>\n\n\n\n<p>Am Telefon und per E-Mail bekommen die Tierhalter daher meist Absagen.<\/p>\n\n\n\n<p>Chancen auf Aufnahme haben meist nur Fundtiere oder Tiere aus Sicherstellungen, f\u00fcr die wir alle immer Pl\u00e4tze freihalten.<\/p>\n\n\n\n<p>Daher stehen sehr viele Menschen vor dem Problem, aus welchen Gr\u00fcnden auch immer, sich von Ihrem Haustier \u201eoffiziell\u201c zu trennen. Viele Menschen erleben hier gr\u00f6\u00dfte seelische Not und wir wissen selten, was wirklich was da dahintersteckt. F\u00fcr uns ist eins klar: wir werden ihn nicht im Stich lassen, ihn bestm\u00f6glich versorgen. Wie es dann mit ihm weitergeht \u2013 wir werden Euch dazu engmaschig informieren.<\/p>\n\n\n\n<p>Aber: wir distanzieren uns von \u00fcblen Kommentaren und verurteilen niemand.<\/p>\n\n\n\n<p>\u00dcbrigens, der Hund hei\u00dft Balu und ist jetzt mit Zyna gemeinsam in einem Gehege. Er findet uns auch schon nicht mehr so gruselig und kommt mehr und mehr zur Ruhe. Alles wird gut!<\/p>\n\n\n\n<p>Ihr wollt uns und Balu unterst\u00fctzen? \u00dcber unsere bekannten Wege freuen wir uns jederzeit \u00fcber jede noch so kleine Spende!<\/p>\n\n\n\n<p>Und Balu? Er wird es Euch von Herzen danken.<\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am fr\u00fchen Morgen des 11. Mai wurde bei uns am Tor ein Hund angebunden! Sicherlich ist dies eine unsch\u00f6ne Situation: der Hund verliert seinen Bezugsmenschen, seinen Halt! F\u00fcr uns bedeutet dies Unsicherheit betreffend das Tier, seinen Gesundheitszustand. \u00dcber die steigenden Kosten f\u00fcr uns und die Verantwortung f\u00fcr ein noch unbekannte Tier \u2013 dar\u00fcber brauchen wir&#8230;<\/p>\n","protected":false},"author":29,"featured_media":20288,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":[],"categories":[4],"tags":[143,142],"_links":{"self":[{"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/posts\/20285"}],"collection":[{"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/comments?post=20285"}],"version-history":[{"count":4,"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/posts\/20285\/revisions"}],"predecessor-version":[{"id":20292,"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/posts\/20285\/revisions\/20292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/media\/20288"}],"wp:attachment":[{"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/media?parent=20285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/categories?post=20285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tierschutzhof-karlsruhe.de\/TSHKAWP\/wp-json\/wp\/v2\/tags?post=20285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}